{"id":731,"date":"2026-05-04T12:48:31","date_gmt":"2026-05-04T10:48:31","guid":{"rendered":"https:\/\/pharmanatura.hu\/?page_id=731"},"modified":"2026-05-04T12:49:57","modified_gmt":"2026-05-04T10:49:57","slug":"sutikezelesi-tajekoztato","status":"publish","type":"page","link":"https:\/\/pharmanatura.hu\/de\/sutikezelesi-tajekoztato\/","title":{"rendered":"Cookie-Richtlinie"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"731\" class=\"elementor elementor-731\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-657cbbfa e-flex e-con-boxed e-con e-parent\" data-id=\"657cbbfa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5eaae642 elementor-widget elementor-widget-heading\" data-id=\"5eaae642\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">INFORMATIONEN ZU KEKSEN<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-772beca0 elementor-widget elementor-widget-text-editor\" data-id=\"772beca0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>G\u00fcltig ab: {{HATALYBA_LEPES}}<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebd7331 elementor-widget elementor-widget-text-editor\" data-id=\"ebd7331\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Pr\u00e4ambel<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c439301 elementor-widget elementor-widget-text-editor\" data-id=\"4c439301\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Bitte beachten Sie, dass unsere Website Cookies verwendet, um den Betrieb der Website zu gew\u00e4hrleisten, die Nutzung zu vereinfachen, Aktivit\u00e4ten auf der Website zu verfolgen und relevante Angebote anzuzeigen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2289c0c7 elementor-widget elementor-widget-text-editor\" data-id=\"2289c0c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Bitte lesen Sie das Dokument sorgf\u00e4ltig durch und nutzen Sie die Dienste der Website nur, wenn Sie mit ihnen einverstanden sind und sie als f\u00fcr Sie als Nutzer verbindlich akzeptieren. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f87d50e elementor-widget elementor-widget-text-editor\" data-id=\"7f87d50e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Datenverantwortlicher<\/strong><strong> Ihre Daten<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6386e10d elementor-widget elementor-widget-text-editor\" data-id=\"6386e10d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Name: {{COMPANY_NAME}}<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-809662c elementor-widget elementor-widget-text-editor\" data-id=\"809662c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Hauptsitz: {{CEG_CIM}}<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-230c55d9 elementor-widget elementor-widget-text-editor\" data-id=\"230c55d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Postanschrift: {{CEG_CIM}}<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-840ef76 elementor-widget elementor-widget-text-editor\" data-id=\"840ef76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Steuernummer: {{CEG_ADOSZAM}}<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bc58394 elementor-widget elementor-widget-text-editor\" data-id=\"5bc58394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Firmenregistrierungsnummer: {{CEG_CEGCHEGYZEK}} oder <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47eb034c elementor-widget elementor-widget-text-editor\" data-id=\"47eb034c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Zulassungsnummer f\u00fcr Elektrofahrzeuge: 00000000<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1056dbc3 elementor-widget elementor-widget-text-editor\" data-id=\"1056dbc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Honlap c\u00edme: pharmanatura.hu<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ec72834 elementor-widget elementor-widget-text-editor\" data-id=\"6ec72834\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>E-Mail-Adresse: {{ADMIN_EMAIL}}<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2474cce5 elementor-widget elementor-widget-text-editor\" data-id=\"2474cce5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Telefonnummer: +36 00 000 0000<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab8caed elementor-widget elementor-widget-text-editor\" data-id=\"2ab8caed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Was ist das? <\/strong><strong>c<\/strong><strong>Ookie<\/strong><strong>?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a529531 elementor-widget elementor-widget-text-editor\" data-id=\"2a529531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Ein Cookie ist ein kleines Datenpaket, das von Internetdiensten im Browser gespeichert wird. Es ist eine unverzichtbare Technologie f\u00fcr den Betrieb von Online-Diensten, die ein effizientes und modernes Nutzererlebnis erm\u00f6glicht und von allen g\u00e4ngigen Browsern unterst\u00fctzt wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55409af6 elementor-widget elementor-widget-text-editor\" data-id=\"55409af6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Ein Cookie ist eine kleine Textdatei, die unsere Website an Ihren Browser sendet, um bestimmte Einstellungen zu speichern, die Nutzung der Website zu vereinfachen und uns zu helfen, relevante statistische Informationen \u00fcber Besucher zu erfassen. Manche Cookies enthalten keine personenbezogenen Daten und eignen sich nicht zur Identifizierung einzelner Nutzer, andere hingegen enthalten eine eindeutige Kennung \u2013 eine geheime, zuf\u00e4llig generierte Zahlenfolge \u2013, die auf Ihrem Ger\u00e4t gespeichert wird und somit Ihre Identifizierung gew\u00e4hrleistet. Die G\u00fcltigkeitsdauer jedes Cookies ist in der jeweiligen Cookie-Beschreibung angegeben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13470e70 elementor-widget elementor-widget-text-editor\" data-id=\"13470e70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Wie entsteht es? <\/strong><strong>und ist n\u00fctzlich <\/strong><strong>a <\/strong><strong>c<\/strong><strong>Ookie<\/strong><strong>?<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2109ef02 elementor-widget elementor-widget-text-editor\" data-id=\"2109ef02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Zun\u00e4chst sendet der Client eine Anfrage an den Server. Der Server erstellt daraufhin eine eindeutige Kennung, speichert diese in seiner Datenbank und sendet den so erstellten Cookie mit allen Informationen zur\u00fcck an den Client. Dieser Cookie mit den empfangenen Informationen wird auf dem Client-Rechner gespeichert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2486e55e elementor-widget elementor-widget-text-editor\" data-id=\"2486e55e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Wenn sich der Client-Rechner erneut mit dem Server verbindet, ist der zuvor erstellte und gespeicherte Cookie bereits vorhanden. Der Server vergleicht den Inhalt des empfangenen Cookies mit dem Inhalt des gespeicherten Cookies. Dadurch l\u00e4sst sich beispielsweise ein angemeldeter, registrierter Benutzer leicht identifizieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-739c9de6 elementor-widget elementor-widget-text-editor\" data-id=\"739c9de6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Betroffen <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-747c6c3d elementor-widget elementor-widget-text-editor\" data-id=\"747c6c3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Nat\u00fcrliche Personen, die die Website des Verantwortlichen besuchen<strong>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3292d787 elementor-widget elementor-widget-text-editor\" data-id=\"3292d787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Zweck der Datenverarbeitung<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d073444 elementor-widget elementor-widget-text-editor\" data-id=\"d073444\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Wir unterscheiden drei Arten von Cookies nach dem Zweck der Datenverarbeitung: Cookies, die f\u00fcr den Betrieb notwendig sind, Cookies f\u00fcr statistische Zwecke und Cookies f\u00fcr Marketingzwecke.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30692c82 elementor-widget elementor-widget-text-editor\" data-id=\"30692c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Rechtsgrundlage f\u00fcr die Datenverarbeitung<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-337add31 elementor-widget elementor-widget-text-editor\" data-id=\"337add31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Im Falle von Cookies f\u00fcr statistische und Marketingzwecke ist Ihre Einwilligung gem\u00e4\u00df Artikel 6 Absatz 1 Buchstabe a DSGVO erforderlich, und im Falle von Cookies, die f\u00fcr den Betrieb der Website notwendig sind, ist das berechtigte Interesse erforderlich, um den Betrieb der Website gem\u00e4\u00df Artikel 6 Absatz 1 Buchstabe f DSGVO zu gew\u00e4hrleisten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74466145 elementor-widget elementor-widget-text-editor\" data-id=\"74466145\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Der Verantwortliche f\u00fcr die Datenverarbeitung informiert den Nutzer beim ersten Besuch \u00fcber die Verwendung von Cookies, die eine Einwilligung erfordern (sofern die Datenverarbeitung mit dem Besuch der Website beginnt), und bittet um dessen Einwilligung. Die Annahme von Cookies, die eine Einwilligung erfordern, ist nicht verpflichtend. Der Verantwortliche \u00fcbernimmt jedoch keine Haftung, falls die Website nicht wie erwartet funktioniert, wenn Cookies nicht zugelassen sind.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a638bf0 elementor-widget elementor-widget-text-editor\" data-id=\"6a638bf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Der Datenverantwortliche verwendet keine Cookies und gestattet auch keine, die es Dritten erm\u00f6glichen, Daten ohne die Zustimmung des Nutzers zu sammeln.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e6df87c elementor-widget elementor-widget-text-editor\" data-id=\"5e6df87c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>M<\/strong><strong>f\u00fcr den Betrieb <\/strong><strong>notwendig<\/strong><strong> <\/strong><strong>Cookies<\/strong><strong>-k<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-193e4587 elementor-widget elementor-widget-text-editor\" data-id=\"193e4587\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Diese Cookies sind f\u00fcr die Nutzung der Website unerl\u00e4sslich und erm\u00f6glichen deren grundlegende Funktionen. Ohne sie stehen Ihnen viele Funktionen der Website nicht zur Verf\u00fcgung. Die Lebensdauer dieser Cookies ist auf die Dauer der jeweiligen Sitzung beschr\u00e4nkt. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39b7006e elementor-widget elementor-widget-text-editor\" data-id=\"39b7006e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Arbeitssitzung <\/strong><strong>Cookies<\/strong><strong>: <\/strong>Diese Cookies speichern den Standort des Besuchers, die Browsersprache und die Zahlungsw\u00e4hrung. Ihre Lebensdauer endet mit dem Schlie\u00dfen des Browsers oder betr\u00e4gt maximal 2 Stunden. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-263b0cb4 elementor-widget elementor-widget-text-editor\" data-id=\"263b0cb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Cookies<\/strong><strong> Annahme <\/strong><strong>Cookies<\/strong><strong>: <\/strong>Beim Besuch der Website akzeptieren Sie die Speicherung von Cookies im Warnfenster. Die G\u00fcltigkeitsdauer betr\u00e4gt 365 Tage. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47d328a9 elementor-widget elementor-widget-text-editor\" data-id=\"47d328a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>PHPSESSID<\/strong><strong>:<\/strong><strong> <\/strong>Dient zur Identifizierung des Logins. Cookie-Lebensdauer: die Dauer der Sitzung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c275889 elementor-widget elementor-widget-text-editor\" data-id=\"3c275889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>F\u00fcr statistische Zwecke <\/strong><strong>Cookies<\/strong><strong>-k<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-303a62cd elementor-widget elementor-widget-text-editor\" data-id=\"303a62cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Google <\/strong><strong>Analysen<\/strong><strong> <\/strong><strong>Cookies<\/strong><strong>: <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-402da0ac elementor-widget elementor-widget-text-editor\" data-id=\"402da0ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Google Analytics ist Googles Analysetool, das Website- und App-Betreibern ein genaueres Bild der Aktivit\u00e4ten ihrer Besucher vermittelt. Der Dienst verwendet m\u00f6glicherweise Cookies, um Informationen zu sammeln und statistische Daten zur Website-Nutzung zu erstellen, ohne die Besucher dabei individuell zu identifizieren. Das wichtigste Cookie von Google Analytics ist das \u201e__ga\u201d-Cookie. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3565d278 elementor-widget elementor-widget-text-editor\" data-id=\"3565d278\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Zus\u00e4tzlich zur Erfassung statistischer Daten \u00fcber die Website-Nutzung kann Google Analytics zusammen mit einigen der oben beschriebenen Werbe-Cookies auch dazu verwendet werden, relevantere Anzeigen in Google-Produkten (wie der Google-Suche) und im gesamten Web anzuzeigen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f1bbab elementor-widget elementor-widget-text-editor\" data-id=\"7f1bbab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Im Einwilligungsformular, das beim ersten Besuch der Website erscheint, k\u00f6nnen Sie Werbefunktionen ablehnen, gleichzeitig aber der Datenverarbeitung zu statistischen Zwecken zustimmen. In diesem Fall stehen die von Google Analytics erfassten Daten ausschlie\u00dflich f\u00fcr die Website-Besuchsstatistik zur Verf\u00fcgung, und die Nutzung zu Werbezwecken ist deaktiviert. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-201bf3a9 elementor-widget elementor-widget-text-editor\" data-id=\"201bf3a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Um die Benutzererfahrung zu verbessern <\/strong><strong>Cookies<\/strong><strong>-S: <\/strong>Diese Cookies sammeln Informationen \u00fcber die Nutzung der Website durch den Nutzer, beispielsweise welche Seiten am h\u00e4ufigsten besucht werden oder welche Fehlermeldungen von der Website empfangen werden. Diese Cookies erfassen keine Informationen, die den Besucher identifizieren; sie arbeiten mit rein allgemeinen, anonymen Daten. Die gewonnenen Daten werden verwendet, um die Leistung der Website zu verbessern. Die Lebensdauer dieser Cookies ist auf die Dauer der jeweiligen Sitzung beschr\u00e4nkt. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dbaa2f8 elementor-widget elementor-widget-text-editor\" data-id=\"4dbaa2f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Zuletzt angesehenes Produkt <\/strong><strong>Cookies<\/strong><strong>: <\/strong>Es speichert die Produkte, die der Besucher zuletzt angesehen hat. Ihre Lebensdauer betr\u00e4gt 60 Tage. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74a78c13 elementor-widget elementor-widget-text-editor\" data-id=\"74a78c13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Korb <\/strong><strong>Cookies<\/strong><strong>: <\/strong>Es speichert die dem Warenkorb hinzugef\u00fcgten Produkte. Seine Lebensdauer betr\u00e4gt 365 Tage. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fee162e elementor-widget elementor-widget-text-editor\" data-id=\"1fee162e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Zu Marketingzwecken <\/strong><strong>Cookies<\/strong><strong>-k<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-637fb64b elementor-widget elementor-widget-text-editor\" data-id=\"637fb64b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Google <\/strong><strong>Anzeigen<\/strong><strong> <\/strong><strong>Cookies<\/strong><strong> <\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10063df4 elementor-widget elementor-widget-text-editor\" data-id=\"10063df4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Wenn ein Besucher unserer Website die Datenverarbeitung zu Marketingzwecken in der daraufhin angezeigten Einwilligungsmeldung akzeptiert, wird der Besucher in die Remarketing-Liste aufgenommen, typischerweise mithilfe von Cookie-Kennungen. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e62eb43 elementor-widget elementor-widget-text-editor\" data-id=\"e62eb43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Google verwendet diese Kennungen, um Anzeigen zu personalisieren, beispielsweise um Ihre letzten Suchanfragen, Ihre vorherigen Interaktionen mit Anzeigen oder Suchergebnissen einzelner Werbetreibender sowie Ihre Besuche auf den Websites der Werbetreibenden zu speichern. Die Conversion-Tracking-Funktion von Google Ads verwendet Cookies oder, mit Ihrer Einwilligung, die E-Mail-Adresse, die Sie bei der Bestellung angegeben haben. Die E-Mail-Adresse wird mittels einer Einweg-Verschl\u00fcsselung (SHA-256-Hash) an Google \u00fcbermittelt. Dadurch kann Google Ihr Google-Profil identifizieren, jedoch nicht Ihre E-Mail-Adresse ermitteln, sofern Sie diese nicht bereits in einem Google-Profil hinterlegt haben. Cookies werden auf dem Computer des Nutzers gespeichert, um Verk\u00e4ufe und andere Conversions zu erfassen, die durch das Anklicken einer Anzeige generiert werden. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8c048e elementor-widget elementor-widget-text-editor\" data-id=\"b8c048e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Zu den g\u00e4ngigen Anwendungsbereichen von Werbe-Cookies geh\u00f6ren: die Auswahl von Anzeigen basierend auf der Relevanz f\u00fcr den jeweiligen Nutzer, die Verbesserung der Berichterstattung zur Kampagnenleistung und die Vermeidung der Anzeige von Anzeigen, die ein Nutzer bereits angesehen hat. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4741c97b elementor-widget elementor-widget-text-editor\" data-id=\"4741c97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Weitere Informationen: https:\/\/business.safety.google\/privacy\/ <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7743d3f6 elementor-widget elementor-widget-text-editor\" data-id=\"7743d3f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>Remarketing<\/strong><strong> <\/strong><strong>Cookies<\/strong><strong>-S: <\/strong>Sie k\u00f6nnen fr\u00fcheren Besuchern oder Nutzern angezeigt werden, wenn diese andere Websites im Google Displaynetzwerk besuchen oder nach Begriffen suchen, die mit Ihren Produkten oder Dienstleistungen in Zusammenhang stehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ff6add6 elementor-widget elementor-widget-text-editor\" data-id=\"7ff6add6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'><strong>A <\/strong><strong>Cookies<\/strong><strong>Erm\u00f6glichen und Verwalten<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10aea2f0 elementor-widget elementor-widget-text-editor\" data-id=\"10aea2f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Die meisten der am h\u00e4ufigsten verwendeten Internetbrowser (Chrome, Firefox, Edge, Explorer, Opera, Safari usw.) akzeptieren und erlauben das Herunterladen und Verwenden von Cookies standardm\u00e4\u00dfig. Es liegt jedoch im Ermessen des Benutzers, diese durch \u00c4nderung der Browsereinstellungen abzulehnen oder zu deaktivieren. Der Benutzer kann auch bereits auf dem Computer gespeicherte Cookies l\u00f6schen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1515c9cd elementor-widget elementor-widget-text-editor\" data-id=\"1515c9cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Das Hilfemen\u00fc jedes Browsers bietet weitere Informationen zur Verwendung von Cookies. Nachfolgend haben wir zusammengestellt, wie Sie Cookies in den einzelnen Browsern systemweit deaktivieren k\u00f6nnen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2238a9ca elementor-widget elementor-widget-text-editor\" data-id=\"2238a9ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Chrom:  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-368253f1 elementor-widget elementor-widget-text-editor\" data-id=\"368253f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Firefox:  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-563461d4 elementor-widget elementor-widget-text-editor\" data-id=\"563461d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Rand:    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78d49c4d elementor-widget elementor-widget-text-editor\" data-id=\"78d49c4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Internet Explorer:  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36c432bf elementor-widget elementor-widget-text-editor\" data-id=\"36c432bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Oper:  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-167e37b1 elementor-widget elementor-widget-text-editor\" data-id=\"167e37b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style='font-size:15px;line-height:1.8;color:#444444;margin-bottom:12px;'>Safari:  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>S\u00dcTIKEZEL\u00c9SI T\u00c1J\u00c9KOZTAT\u00d3 Hat\u00e1lyba l\u00e9p\u00e9s ideje:\u00a0{{HATALYBA_LEPES}} Preambulum T\u00e1j\u00e9koztatjuk, hogy a weboldalunk s\u00fctiket (cookie-k) haszn\u00e1l a honlap m\u0171k\u00f6dtet\u00e9se, haszn\u00e1lat\u00e1nak megk\u00f6nny\u00edt\u00e9se, a weboldalon v\u00e9gzett tev\u00e9kenys\u00e9g nyomon k\u00f6vet\u00e9se \u00e9s relev\u00e1ns aj\u00e1nlatok megjelen\u00edt\u00e9se \u00e9rdek\u00e9ben. K\u00e9rj\u00fck, hogy a dokumentumot figyelmesen olvassa el, \u00e9s csak akkor vegye ig\u00e9nybe a honlap szolg\u00e1ltat\u00e1sait, amennyiben azzal egyet\u00e9rt, \u00e9s azokat \u00d6nre, mint felhaszn\u00e1l\u00f3ra n\u00e9zve k\u00f6telez\u0151 \u00e9rv\u00e9ny\u0171nek [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-731","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.1 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3 | Pharma Natura Kft.<\/title>\n<meta name=\"description\" content=\"Pharma Natura Kft. s\u00fctikre vonatkoz\u00f3 adatkezel\u00e9si szab\u00e1lyai. Tudjon meg t\u00f6bbet s\u00fctizeink haszn\u00e1lat\u00e1r\u00f3l \u00e9s adatv\u00e9delmi gyakorlatunkr\u00f3l.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pharmanatura.hu\/de\/sutikezelesi-tajekoztato\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3\" \/>\n<meta property=\"og:description\" content=\"Pharma Natura Kft. s\u00fctikre vonatkoz\u00f3 adatkezel\u00e9si szab\u00e1lyai. Tudjon meg t\u00f6bbet s\u00fctizeink haszn\u00e1lat\u00e1r\u00f3l \u00e9s adatv\u00e9delmi gyakorlatunkr\u00f3l.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pharmanatura.hu\/de\/sutikezelesi-tajekoztato\/\" \/>\n<meta property=\"og:site_name\" content=\"Pharma Natura Kft.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T10:49:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/sutikezelesi-tajekoztato\\\/\",\"url\":\"https:\\\/\\\/pharmanatura.hu\\\/sutikezelesi-tajekoztato\\\/\",\"name\":\"S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3 | Pharma Natura Kft.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/#website\"},\"datePublished\":\"2026-05-04T10:48:31+00:00\",\"dateModified\":\"2026-05-04T10:49:57+00:00\",\"description\":\"Pharma Natura Kft. s\u00fctikre vonatkoz\u00f3 adatkezel\u00e9si szab\u00e1lyai. Tudjon meg t\u00f6bbet s\u00fctizeink haszn\u00e1lat\u00e1r\u00f3l \u00e9s adatv\u00e9delmi gyakorlatunkr\u00f3l.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/sutikezelesi-tajekoztato\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pharmanatura.hu\\\/sutikezelesi-tajekoztato\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/sutikezelesi-tajekoztato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/pharmanatura.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/#website\",\"url\":\"https:\\\/\\\/pharmanatura.hu\\\/\",\"name\":\"Pharma Natura Kft.\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pharmanatura.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/#organization\",\"name\":\"Pharma Natura Kft.\",\"url\":\"https:\\\/\\\/pharmanatura.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pharmanatura.hu\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/pharma-natura-modern-horizontal-fenyozold2-2.png\",\"contentUrl\":\"https:\\\/\\\/pharmanatura.hu\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/pharma-natura-modern-horizontal-fenyozold2-2.png\",\"width\":2160,\"height\":360,\"caption\":\"Pharma Natura Kft.\"},\"image\":{\"@id\":\"https:\\\/\\\/pharmanatura.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3 | Pharma Natura Kft.","description":"Pharma Natura Kft. s\u00fctikre vonatkoz\u00f3 adatkezel\u00e9si szab\u00e1lyai. Tudjon meg t\u00f6bbet s\u00fctizeink haszn\u00e1lat\u00e1r\u00f3l \u00e9s adatv\u00e9delmi gyakorlatunkr\u00f3l.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pharmanatura.hu\/de\/sutikezelesi-tajekoztato\/","og_locale":"de_DE","og_type":"article","og_title":"S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3","og_description":"Pharma Natura Kft. s\u00fctikre vonatkoz\u00f3 adatkezel\u00e9si szab\u00e1lyai. Tudjon meg t\u00f6bbet s\u00fctizeink haszn\u00e1lat\u00e1r\u00f3l \u00e9s adatv\u00e9delmi gyakorlatunkr\u00f3l.","og_url":"https:\/\/pharmanatura.hu\/de\/sutikezelesi-tajekoztato\/","og_site_name":"Pharma Natura Kft.","article_modified_time":"2026-05-04T10:49:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pharmanatura.hu\/sutikezelesi-tajekoztato\/","url":"https:\/\/pharmanatura.hu\/sutikezelesi-tajekoztato\/","name":"S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3 | Pharma Natura Kft.","isPartOf":{"@id":"https:\/\/pharmanatura.hu\/#website"},"datePublished":"2026-05-04T10:48:31+00:00","dateModified":"2026-05-04T10:49:57+00:00","description":"Pharma Natura Kft. s\u00fctikre vonatkoz\u00f3 adatkezel\u00e9si szab\u00e1lyai. Tudjon meg t\u00f6bbet s\u00fctizeink haszn\u00e1lat\u00e1r\u00f3l \u00e9s adatv\u00e9delmi gyakorlatunkr\u00f3l.","breadcrumb":{"@id":"https:\/\/pharmanatura.hu\/sutikezelesi-tajekoztato\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pharmanatura.hu\/sutikezelesi-tajekoztato\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pharmanatura.hu\/sutikezelesi-tajekoztato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/pharmanatura.hu\/"},{"@type":"ListItem","position":2,"name":"S\u00fctikezel\u00e9si t\u00e1j\u00e9koztat\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/pharmanatura.hu\/#website","url":"https:\/\/pharmanatura.hu\/","name":"Pharma Natura Kft.","description":"","publisher":{"@id":"https:\/\/pharmanatura.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pharmanatura.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/pharmanatura.hu\/#organization","name":"Pharma Natura Kft.","url":"https:\/\/pharmanatura.hu\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/pharmanatura.hu\/#\/schema\/logo\/image\/","url":"https:\/\/pharmanatura.hu\/wp-content\/uploads\/2026\/09\/pharma-natura-modern-horizontal-fenyozold2-2.png","contentUrl":"https:\/\/pharmanatura.hu\/wp-content\/uploads\/2026\/09\/pharma-natura-modern-horizontal-fenyozold2-2.png","width":2160,"height":360,"caption":"Pharma Natura Kft."},"image":{"@id":"https:\/\/pharmanatura.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/pages\/731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/comments?post=731"}],"version-history":[{"count":4,"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/pages\/731\/revisions"}],"predecessor-version":[{"id":737,"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/pages\/731\/revisions\/737"}],"wp:attachment":[{"href":"https:\/\/pharmanatura.hu\/de\/wp-json\/wp\/v2\/media?parent=731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}